{"id":854,"date":"2022-02-07T07:49:33","date_gmt":"2022-02-07T07:49:33","guid":{"rendered":"https:\/\/vnahealth.com\/\/service\/sick-care\/"},"modified":"2025-12-17T14:24:11","modified_gmt":"2025-12-17T20:24:11","slug":"sick-care","status":"publish","type":"service","link":"https:\/\/vnahealth.com\/es\/service\/sick-care\/","title":{"rendered":"Atenci\u00f3n por Enfermedad"},"content":{"rendered":"<h2>Atenci\u00f3n ambulatoria por enfermedad en los suburbios de Chicago<\/h2>\n<p>VNA Health Care puede ayudarle si est\u00e1 enfermo o tiene una lesi\u00f3n menor. En lugar de esperar por horas en un centro de urgencias o en la sala de emergencias, puede acudir al centro VNA m\u00e1s cercano para recibir un servicio m\u00e1s r\u00e1pido a un precio accesible.<\/p>\n<p>Los pacientes (nuevos y recurrentes) tambi\u00e9n pueden reservar una cita el mismo d\u00eda usando nuestro portal online llamando a VNA al <a href=\"tel:(630)4916530\">(630) 491-6530<\/a>.<\/p>\n<h2>\u00bfQu\u00e9 es la atenci\u00f3n ambulatoria?<\/h2>\n<p>La atenci\u00f3n ambulatoria se refiere a los servicios m\u00e9dicos que no requieren que el paciente sea admitido en un hospital o permanezca en observaci\u00f3n durante la noche. En lugar de ello, el paciente recibe atenci\u00f3n en un centro m\u00e9dico o cl\u00ednica y puede regresar a su hogar el mismo d\u00eda.<\/p>\n<h3>Atenci\u00f3n ambulatoria por enfermedad<\/h3>\n<p>La atenci\u00f3n ambulatoria por enfermedad se refiere a la atenci\u00f3n m\u00e9dica que se proporciona a los pacientes con enfermedades o afecciones que no requieren hospitalizaci\u00f3n. Este tipo de atenci\u00f3n incluye visitas a cl\u00ednicas o consultorios donde los pacientes pueden recibir diagn\u00f3stico, tratamiento y seguimiento sin necesidad de quedarse en el hospital.<\/p>\n<p>En VNA, usted puede recibir atenci\u00f3n ambulatoria para enfermedades y lesiones menores sin necesidad de programar una cita. Simplemente acuda a uno de nuestros centros durante nuestro horario de atenci\u00f3n. En algunos casos puede ser m\u00e1s conveniente programar un turno. Usted puede hacerlo usando el portal de turnos o llamando por tel\u00e9fono.<\/p>\n<h2>\u00bfEn qu\u00e9 caso necesito atenci\u00f3n ambulatoria por enfermedad?<\/h2>\n<p>La atenci\u00f3n ambulatoria por enfermedad es para situaciones que requieren atenci\u00f3n m\u00e9dica pero que no son graves ni ponen en peligro su vida. Los pacientes suelen acudir a los centros VNA en casos de:<\/p>\n<ul>\n<li>Gripe<\/li>\n<li>Fiebre inferior a 104\u00b0F<\/li>\n<li>Resfriados y tos<\/li>\n<li>Esguinces y distensiones<\/li>\n<li>Dolores de cabeza y migra\u00f1as<\/li>\n<li>Infecciones de o\u00eddo<\/li>\n<li>Condiciones respiratorias superiores (sinusitis, bronquitis)<\/li>\n<li>Erupciones o infecciones de la piel que no responden a remedios caseros<\/li>\n<li>Ojos rojos, hinchados o con picaz\u00f3n que no mejoran por s\u00ed solos<\/li>\n<li>Otras enfermedades comunes<\/li>\n<\/ul>\n<p>Los centros VNA tambi\u00e9n tienen servicios de laboratorio en el lugar (con y sin turno). Realizamos an\u00e1lisis de sangre, ex\u00e1menes de salud, pruebas de embarazo, pruebas de Papanicolaou y mucho m\u00e1s.<\/p>\n<p>Si est\u00e1 experimentando una emergencia m\u00e9dica o condici\u00f3n de salud que ponga en peligro su vida, por favor visite la sala de emergencias m\u00e1s cercana o llame al 911. Si usted viene al centro VNA y su caso requiere atenci\u00f3n de emergencia, lo dirigiremos a la sala de emergencias.<\/p>\n<h2>Horario de atenci\u00f3n ambulatoria por enfermedad<\/h2>\n<p>La atenci\u00f3n el mismo d\u00eda est\u00e1 disponible en todas los centros VNA donde se ofrece atenci\u00f3n por enfermedad. Consulte el horario de atenci\u00f3n de cada centro antes de acercarse. Aunque no necesita una cita, puede ser conveniente programar una para mayor comodidad. Tenemos disponibilidad para citas temprano por la ma\u00f1ana, por la tarde y durante los fines de semana.<\/p>\n<p>Estamos ubicados en <a href=\"https:\/\/vnahealth.com\/es\/locations\/\">varias \u00e1reas fuera de Chicago<\/a>, incluyendo Aurora, Bensenville, Bolingbrook, Carol Stream, Elgin, Joliet, Romeoville, Villa Park y Wheaton. No importa si usted tiene o no seguro m\u00e9dico: todos los pacientes reciben atenci\u00f3n de calidad con VNA.<\/p>\n<h2>Consiga atenci\u00f3n a los enfermos en su centro VNA<\/h2>\n<p>Usted puede atenderse por enfermedad en cualquier centro de VNA Health Care aunque su proveedor de salud sea otro. Nuestros proveedores de atenci\u00f3n primaria incluyen m\u00e9dicos y enfermeros practicantes especializados en medicina interna y de familia, adem\u00e1s de podiatras, obstetras, ginec\u00f3logos, pediatras y muchos otros especialistas.<\/p>\n<h2>Preguntas sobre nuestros servicios de atenci\u00f3n ambulatoria por enfermedad<\/h2>\n<h3>\u00bfQu\u00e9 hago si no tengo seguro y necesito atenci\u00f3n m\u00e9dica?<\/h3>\n<p>Usted puede recibir atenci\u00f3n m\u00e9dica en VNA Health Care aunque no tenga seguro. Podemos ofrecerle una tarifa reducida en base a sus ingresos o el tama\u00f1o de su familia. Nuestro equipo tambi\u00e9n puede ayudarle a tramitar beneficios de salud (en caso de que usted califique).<\/p>\n<h3>\u00bfCu\u00e1l es la diferencia entre atenci\u00f3n ambulatoria y hospitalaria?<\/h3>\n<p>La atenci\u00f3n ambulatoria se refiere a los servicios m\u00e9dicos que se brindan sin que el paciente necesite ser ingresado en el hospital. Esto incluye consultas m\u00e9dicas, tratamientos y procedimientos que no requieren observaci\u00f3n o estancia prolongada. El paciente recibe atenci\u00f3n y puede regresar a su hogar el mismo d\u00eda. En VNA, atenci\u00f3n ambulatoria por enfermedad se refiere a la atenci\u00f3n en el momento para pacientes con enfermedades y lesiones menores.<\/p>\n<p>La atenci\u00f3n hospitalaria implica que el paciente sea ingresado en el hospital para recibir atenci\u00f3n m\u00e9dica, generalmente cuando se trata de condiciones graves o que requieren supervisi\u00f3n continua. En este caso, el paciente debe pasar la noche (o m\u00e1s) en el hospital para recibir el tratamiento necesario. VNA no ofrece este servicio.<\/p>\n<h3>\u00bfCu\u00e1l es la diferencia entre la atenci\u00f3n ambulatoria por enfermedad y la atenci\u00f3n de urgencias?<\/h3>\n<p>Los servicios de atenci\u00f3n ambulatoria por enfermedad y la atenci\u00f3n de urgencias son parecidos. En VNA, la atenci\u00f3n ambulatoria por enfermedad est\u00e1 disponible en todos nuestros centros, mientras que la atenci\u00f3n de urgencias s\u00f3lo est\u00e1 disponible en nuestro <a href=\"https:\/\/vnahealth.com\/es\/location\/primary-care-center-in-aurora-weston-ave\/\">centro de Weston Avenue en Aurora<\/a>. Los servicios de atenci\u00f3n de urgencia incluyen los mismos servicios que la atenci\u00f3n por enfermedad y otros servicios adicionales: suturas, radiograf\u00edas de huesos y t\u00f3rax, yeso blando, extracci\u00f3n de cuerpos extra\u00f1os, abrasiones corneales menores (la superficie del ojo) y quemaduras menores.<\/p>\n<h3 style=\"padding: 56.25% 0 0 0; position: relative;\"><iframe style=\"position: absolute; top: 0; left: 0; width: 100%; height: 100%;\" src=\"https:\/\/player.vimeo.com\/video\/227769729?h=c11041d3e6&amp;title=0&amp;byline=0\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/h3>\n<p><script src=\"https:\/\/player.vimeo.com\/api\/player.js\"><\/script><\/p>\n","protected":false},"featured_media":0,"parent":0,"menu_order":83,"template":"","class_list":["post-854","service","type-service","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Atenci\u00f3n Ambulatoria por Enfermedad | VNA Health Care<\/title>\n<meta name=\"description\" content=\"Acuda a los centros VNA para conseguir atenci\u00f3n ambulatoria para enfermedades y lesiones menores. Tenemos 15 centros en los suburbios de Chicago.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vnahealth.com\/es\/service\/sick-care\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Atenci\u00f3n Ambulatoria por Enfermedad | VNA Health Care\" \/>\n<meta property=\"og:description\" content=\"Acuda a los centros VNA para conseguir atenci\u00f3n ambulatoria para enfermedades y lesiones menores. Tenemos 15 centros en los suburbios de Chicago.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vnahealth.com\/es\/service\/sick-care\/\" \/>\n<meta property=\"og:site_name\" content=\"VNA Health Care\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-17T20:24:11+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vnahealth.com\\\/es\\\/service\\\/sick-care\\\/\",\"url\":\"https:\\\/\\\/vnahealth.com\\\/es\\\/service\\\/sick-care\\\/\",\"name\":\"Atenci\u00f3n Ambulatoria por Enfermedad | VNA Health Care\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vnahealth.com\\\/es\\\/#website\"},\"datePublished\":\"2022-02-07T07:49:33+00:00\",\"dateModified\":\"2025-12-17T20:24:11+00:00\",\"description\":\"Acuda a los centros VNA para conseguir atenci\u00f3n ambulatoria para enfermedades y lesiones menores. Tenemos 15 centros en los suburbios de Chicago.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vnahealth.com\\\/es\\\/service\\\/sick-care\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vnahealth.com\\\/es\\\/service\\\/sick-care\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vnahealth.com\\\/es\\\/service\\\/sick-care\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/vnahealth.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Services\",\"item\":\"https:\\\/\\\/vnahealth.com\\\/es\\\/service\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Atenci\u00f3n por Enfermedad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vnahealth.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vnahealth.com\\\/es\\\/\",\"name\":\"VNA Health Care\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/vnahealth.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vnahealth.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vnahealth.com\\\/es\\\/#organization\",\"name\":\"VNA Health Care\",\"url\":\"https:\\\/\\\/vnahealth.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vnahealth.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/vnahealth.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Logo.svg\",\"contentUrl\":\"https:\\\/\\\/vnahealth.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Logo.svg\",\"width\":218,\"height\":45,\"caption\":\"VNA Health Care\"},\"image\":{\"@id\":\"https:\\\/\\\/vnahealth.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Atenci\u00f3n Ambulatoria por Enfermedad | VNA Health Care","description":"Acuda a los centros VNA para conseguir atenci\u00f3n ambulatoria para enfermedades y lesiones menores. Tenemos 15 centros en los suburbios de Chicago.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vnahealth.com\/es\/service\/sick-care\/","og_locale":"es_ES","og_type":"article","og_title":"Atenci\u00f3n Ambulatoria por Enfermedad | VNA Health Care","og_description":"Acuda a los centros VNA para conseguir atenci\u00f3n ambulatoria para enfermedades y lesiones menores. Tenemos 15 centros en los suburbios de Chicago.","og_url":"https:\/\/vnahealth.com\/es\/service\/sick-care\/","og_site_name":"VNA Health Care","article_modified_time":"2025-12-17T20:24:11+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/vnahealth.com\/es\/service\/sick-care\/","url":"https:\/\/vnahealth.com\/es\/service\/sick-care\/","name":"Atenci\u00f3n Ambulatoria por Enfermedad | VNA Health Care","isPartOf":{"@id":"https:\/\/vnahealth.com\/es\/#website"},"datePublished":"2022-02-07T07:49:33+00:00","dateModified":"2025-12-17T20:24:11+00:00","description":"Acuda a los centros VNA para conseguir atenci\u00f3n ambulatoria para enfermedades y lesiones menores. Tenemos 15 centros en los suburbios de Chicago.","breadcrumb":{"@id":"https:\/\/vnahealth.com\/es\/service\/sick-care\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vnahealth.com\/es\/service\/sick-care\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/vnahealth.com\/es\/service\/sick-care\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/vnahealth.com\/es\/"},{"@type":"ListItem","position":2,"name":"Services","item":"https:\/\/vnahealth.com\/es\/service\/"},{"@type":"ListItem","position":3,"name":"Atenci\u00f3n por Enfermedad"}]},{"@type":"WebSite","@id":"https:\/\/vnahealth.com\/es\/#website","url":"https:\/\/vnahealth.com\/es\/","name":"VNA Health Care","description":"","publisher":{"@id":"https:\/\/vnahealth.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vnahealth.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vnahealth.com\/es\/#organization","name":"VNA Health Care","url":"https:\/\/vnahealth.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vnahealth.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/vnahealth.com\/wp-content\/uploads\/2021\/12\/Logo.svg","contentUrl":"https:\/\/vnahealth.com\/wp-content\/uploads\/2021\/12\/Logo.svg","width":218,"height":45,"caption":"VNA Health Care"},"image":{"@id":"https:\/\/vnahealth.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/vnahealth.com\/es\/wp-json\/wp\/v2\/service\/854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vnahealth.com\/es\/wp-json\/wp\/v2\/service"}],"about":[{"href":"https:\/\/vnahealth.com\/es\/wp-json\/wp\/v2\/types\/service"}],"version-history":[{"count":4,"href":"https:\/\/vnahealth.com\/es\/wp-json\/wp\/v2\/service\/854\/revisions"}],"predecessor-version":[{"id":37426,"href":"https:\/\/vnahealth.com\/es\/wp-json\/wp\/v2\/service\/854\/revisions\/37426"}],"wp:attachment":[{"href":"https:\/\/vnahealth.com\/es\/wp-json\/wp\/v2\/media?parent=854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}