{"id":10006896,"date":"2024-01-09T15:50:40","date_gmt":"2024-01-09T21:50:40","guid":{"rendered":"https:\/\/vnahealth.com\/\/?post_type=tribe_events&#038;p=32191"},"modified":"2024-02-06T15:37:50","modified_gmt":"2024-02-06T21:37:50","slug":"nutricion-familiar","status":"publish","type":"tribe_events","link":"https:\/\/vnahealth.com\/es\/event\/nutricion-familiar\/2028-07-03\/","title":{"rendered":"Nutrici\u00f3n Familiar"},"content":{"rendered":"<p>Todos los h\u00e1bitos saludables comienzan desde una edad temprana. \u00danase a nuestra clase para aprender m\u00e1s sobre c\u00f3mo puede ayudar a mejorar y mantener la buena salud de su familia a trav\u00e9s de una nutrici\u00f3n adecuada y actividad f\u00edsica. Usted aprender\u00e1 los principales grupos de alimentos, obtendr\u00e1 ideas de refrigerios y c\u00f3mo puede incluir a su hijo en la preparaci\u00f3n de alimentos. \u00a1Los ni\u00f1os son bienvenidos!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Todos los h\u00e1bitos saludables comienzan desde una edad temprana. \u00danase a nuestra clase para aprender m\u00e1s sobre c\u00f3mo puede ayudar a mejorar y mantener la buena salud de su familia a trav\u00e9s de una nutrici\u00f3n adecuada y actividad f\u00edsica. <\/p>\n","protected":false},"author":7,"featured_media":32192,"template":"","meta":{"_acf_changed":false,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"tags":[],"tribe_events_cat":[],"class_list":["post-10006896","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe-recurring-event","tribe-recurring-event-parent"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nutrici\u00f3n Familiar | VNA Health Care<\/title>\n<meta name=\"description\" content=\"Todos los h\u00e1bitos saludables comienzan desde una edad temprana. \u00danase a nuestra clase para aprender m\u00e1s sobre c\u00f3mo puede ayudar a mejorar y mantener la buena salud de su familia a trav\u00e9s de una nutrici\u00f3n adecuada y actividad f\u00edsica.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nutrici\u00f3n Familiar | VNA Health Care\" \/>\n<meta property=\"og:description\" content=\"Todos los h\u00e1bitos saludables comienzan desde una edad temprana. \u00danase a nuestra clase para aprender m\u00e1s sobre c\u00f3mo puede ayudar a mejorar y mantener la buena salud de su familia a trav\u00e9s de una nutrici\u00f3n adecuada y actividad f\u00edsica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vnahealth.com\/es\/event\/nutricion-familiar\/2028-07-03\/\" \/>\n<meta property=\"og:site_name\" content=\"VNA Health Care\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-06T21:37:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vnahealth.com\/wp-content\/uploads\/2024\/01\/Untitled-design-29.png\" \/>\n\t<meta property=\"og:image:width\" content=\"940\" \/>\n\t<meta property=\"og:image:height\" content=\"788\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vnahealth.com\\\/es\\\/event\\\/nutricion-familiar\\\/2028-07-03\\\/\",\"url\":\"https:\\\/\\\/vnahealth.com\\\/es\\\/event\\\/nutricion-familiar\\\/2028-07-03\\\/\",\"name\":\"Nutrici\u00f3n Familiar | VNA Health Care\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vnahealth.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vnahealth.com\\\/es\\\/event\\\/nutricion-familiar\\\/2028-07-03\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vnahealth.com\\\/es\\\/event\\\/nutricion-familiar\\\/2028-07-03\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vnahealth.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Untitled-design-29.png\",\"datePublished\":\"2024-01-09T21:50:40+00:00\",\"dateModified\":\"2024-02-06T21:37:50+00:00\",\"description\":\"Todos los h\u00e1bitos saludables comienzan desde una edad temprana. \u00danase a nuestra clase para aprender m\u00e1s sobre c\u00f3mo puede ayudar a mejorar y mantener la buena salud de su familia a trav\u00e9s de una nutrici\u00f3n adecuada y actividad f\u00edsica.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vnahealth.com\\\/es\\\/event\\\/nutricion-familiar\\\/2028-07-03\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vnahealth.com\\\/es\\\/event\\\/nutricion-familiar\\\/2028-07-03\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vnahealth.com\\\/es\\\/event\\\/nutricion-familiar\\\/2028-07-03\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vnahealth.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Untitled-design-29.png\",\"contentUrl\":\"https:\\\/\\\/vnahealth.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Untitled-design-29.png\",\"width\":940,\"height\":788},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vnahealth.com\\\/es\\\/event\\\/nutricion-familiar\\\/2028-07-03\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/vnahealth.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eventos\",\"item\":\"https:\\\/\\\/vnahealth.com\\\/es\\\/calendar\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Nutrici\u00f3n Familiar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vnahealth.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vnahealth.com\\\/es\\\/\",\"name\":\"VNA Health Care\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/vnahealth.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vnahealth.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vnahealth.com\\\/es\\\/#organization\",\"name\":\"VNA Health Care\",\"url\":\"https:\\\/\\\/vnahealth.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vnahealth.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/vnahealth.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Logo.svg\",\"contentUrl\":\"https:\\\/\\\/vnahealth.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Logo.svg\",\"width\":218,\"height\":45,\"caption\":\"VNA Health Care\"},\"image\":{\"@id\":\"https:\\\/\\\/vnahealth.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nutrici\u00f3n Familiar | VNA Health Care","description":"Todos los h\u00e1bitos saludables comienzan desde una edad temprana. \u00danase a nuestra clase para aprender m\u00e1s sobre c\u00f3mo puede ayudar a mejorar y mantener la buena salud de su familia a trav\u00e9s de una nutrici\u00f3n adecuada y actividad f\u00edsica.","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Nutrici\u00f3n Familiar | VNA Health Care","og_description":"Todos los h\u00e1bitos saludables comienzan desde una edad temprana. \u00danase a nuestra clase para aprender m\u00e1s sobre c\u00f3mo puede ayudar a mejorar y mantener la buena salud de su familia a trav\u00e9s de una nutrici\u00f3n adecuada y actividad f\u00edsica.","og_url":"https:\/\/vnahealth.com\/es\/event\/nutricion-familiar\/2028-07-03\/","og_site_name":"VNA Health Care","article_modified_time":"2024-02-06T21:37:50+00:00","og_image":[{"width":940,"height":788,"url":"https:\/\/vnahealth.com\/wp-content\/uploads\/2024\/01\/Untitled-design-29.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/vnahealth.com\/es\/event\/nutricion-familiar\/2028-07-03\/","url":"https:\/\/vnahealth.com\/es\/event\/nutricion-familiar\/2028-07-03\/","name":"Nutrici\u00f3n Familiar | VNA Health Care","isPartOf":{"@id":"https:\/\/vnahealth.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vnahealth.com\/es\/event\/nutricion-familiar\/2028-07-03\/#primaryimage"},"image":{"@id":"https:\/\/vnahealth.com\/es\/event\/nutricion-familiar\/2028-07-03\/#primaryimage"},"thumbnailUrl":"https:\/\/vnahealth.com\/wp-content\/uploads\/2024\/01\/Untitled-design-29.png","datePublished":"2024-01-09T21:50:40+00:00","dateModified":"2024-02-06T21:37:50+00:00","description":"Todos los h\u00e1bitos saludables comienzan desde una edad temprana. \u00danase a nuestra clase para aprender m\u00e1s sobre c\u00f3mo puede ayudar a mejorar y mantener la buena salud de su familia a trav\u00e9s de una nutrici\u00f3n adecuada y actividad f\u00edsica.","breadcrumb":{"@id":"https:\/\/vnahealth.com\/es\/event\/nutricion-familiar\/2028-07-03\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vnahealth.com\/es\/event\/nutricion-familiar\/2028-07-03\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vnahealth.com\/es\/event\/nutricion-familiar\/2028-07-03\/#primaryimage","url":"https:\/\/vnahealth.com\/wp-content\/uploads\/2024\/01\/Untitled-design-29.png","contentUrl":"https:\/\/vnahealth.com\/wp-content\/uploads\/2024\/01\/Untitled-design-29.png","width":940,"height":788},{"@type":"BreadcrumbList","@id":"https:\/\/vnahealth.com\/es\/event\/nutricion-familiar\/2028-07-03\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/vnahealth.com\/es\/"},{"@type":"ListItem","position":2,"name":"Eventos","item":"https:\/\/vnahealth.com\/es\/calendar\/"},{"@type":"ListItem","position":3,"name":"Nutrici\u00f3n Familiar"}]},{"@type":"WebSite","@id":"https:\/\/vnahealth.com\/es\/#website","url":"https:\/\/vnahealth.com\/es\/","name":"VNA Health Care","description":"","publisher":{"@id":"https:\/\/vnahealth.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vnahealth.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vnahealth.com\/es\/#organization","name":"VNA Health Care","url":"https:\/\/vnahealth.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vnahealth.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/vnahealth.com\/wp-content\/uploads\/2021\/12\/Logo.svg","contentUrl":"https:\/\/vnahealth.com\/wp-content\/uploads\/2021\/12\/Logo.svg","width":218,"height":45,"caption":"VNA Health Care"},"image":{"@id":"https:\/\/vnahealth.com\/es\/#\/schema\/logo\/image\/"}}]}},"ticketed":false,"_links":{"self":[{"href":"https:\/\/vnahealth.com\/es\/wp-json\/wp\/v2\/tribe_events\/10006896","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vnahealth.com\/es\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/vnahealth.com\/es\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/vnahealth.com\/es\/wp-json\/wp\/v2\/users\/7"}],"version-history":[{"count":0,"href":"https:\/\/vnahealth.com\/es\/wp-json\/wp\/v2\/tribe_events\/10006896\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vnahealth.com\/es\/wp-json\/wp\/v2\/media\/32192"}],"wp:attachment":[{"href":"https:\/\/vnahealth.com\/es\/wp-json\/wp\/v2\/media?parent=10006896"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vnahealth.com\/es\/wp-json\/wp\/v2\/tags?post=10006896"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/vnahealth.com\/es\/wp-json\/wp\/v2\/tribe_events_cat?post=10006896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}